{"id":20918,"date":"2020-07-07T13:50:17","date_gmt":"2020-07-07T16:50:17","guid":{"rendered":"https:\/\/souzalima.com.br\/blog\/?p=20918"},"modified":"2025-06-06T16:24:22","modified_gmt":"2025-06-06T19:24:22","slug":"como-e-definido-o-posicionamento-da-haste-das-notas","status":"publish","type":"post","link":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/","title":{"rendered":"Como \u00e9 definido o posicionamento da haste das notas?"},"content":{"rendered":"<h2><strong>Como \u00e9 definido o posicionamento da haste das notas?<\/strong><\/h2>\n<p>O posicionamento da haste \u00e9 um assunto que os livros de teoria infelizmente respondem parcialmente. Um leitor trouxe uma excelente pergunta.<\/p>\n<p>Vale corrigir, e chamar<strong> notas<\/strong> do sin\u00f4nimo de linguagem musical <strong>figuras de valor positivo<\/strong>. No caso os valores que possuem haste (m\u00ednima, sem\u00ednima, colcheia, semicolcheia, fusa e semifusa).<\/p>\n<p>m primeiro lugar \u00e9 preciso separar o posicionamento da haste em um crit\u00e9rio geral. Esse crit\u00e9rio geral se restringe a escrita de uma \u00fanica voz. \u00c0 primeira vista a haste \u00e9 posicionada conforme o posicionamento da nota nas linhas do pentagrama, independentemente da clave.<\/p>\n<h2><strong>A partir da terceira linha a haste \u00e9 pautada para baixo. A baixo da terceira linha a haste \u00e9 pautada para cima.<\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17027 td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/posicionamento-da-haste.png?resize=696%2C68&amp;ssl=1\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" srcset=\"https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/posicionamento-da-haste.png?w=2171&amp;ssl=1 2171w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/posicionamento-da-haste.png?resize=300%2C29&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/posicionamento-da-haste.png?resize=768%2C75&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/posicionamento-da-haste.png?resize=1024%2C100&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/posicionamento-da-haste.png?resize=696%2C68&amp;ssl=1 696w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/posicionamento-da-haste.png?resize=1068%2C104&amp;ssl=1 1068w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/posicionamento-da-haste.png?w=1392&amp;ssl=1 1392w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/posicionamento-da-haste.png?w=2088&amp;ssl=1 2088w\" alt=\"\" width=\"696\" height=\"68\" data-recalc-dims=\"1\" \/><\/p>\n<p>A terceira linha \u00e9 um ponto equidistante aos dois conceitos, sendo poss\u00edvel encontrar a haste posicionada tanto para baixo quanto para cima. Depende justamente do movimento mel\u00f3dico em que se encontrar, justificando uma boa liga\u00e7\u00e3o dos colchetes. Se o movimento for ascendente haste para baixo, se o movimento for descendente haste para cima.<\/p>\n<p>Mesmo com essa orienta\u00e7\u00e3o que embeleza a partitura, \u00e9 importante dizer que o posicionamento da haste na linha central, para cima ou para baixo, \u00e9 facultativo.<\/p>\n<h2><strong>Mas bem, voc\u00ea toca piano ou viol\u00e3o e n\u00e3o encontra suas partituras assim.<\/strong><\/h2>\n<p>Em instrumentos capazes de emitir duas ou mais vozes simultaneamente a teoria se adapta. Quando duas vozes a voz mais aguda independentemente de onde estiver no pentagrama apresenta hastes para cima. A voz mais grave justo posto apresenta hastes para baixo. Esse mesmo crit\u00e9rio se estende ao piano, duas pautas, que \u00e9 poss\u00edvel escrever a quatro vozes, cada pauta repetir\u00e1 o crit\u00e9rio acima.<\/p>\n<p>Ao viol\u00e3o, quando s\u00e3o tr\u00eas vozes, habitualmente duas hastes se apresentam para baixo e uma haste para cima. Observe em um arranjo que escrevi da cole\u00e7\u00e3o Miniaturas para viol\u00e3o da composi\u00e7\u00e3o de Milton Nascimento \u201c<strong>Ponta de Areia<\/strong>\u201d, a aplica\u00e7\u00e3o do conceito e posicionamento das hastes.<\/p>\n<p>Esse arranjo possui alguns momentos a duas vozes, outros a tr\u00eas vozes. Observe:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17028 td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/Ponta-de-areia-arranjo.png?resize=696%2C1033&amp;ssl=1\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" srcset=\"https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/Ponta-de-areia-arranjo.png?w=2171&amp;ssl=1 2171w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/Ponta-de-areia-arranjo.png?resize=202%2C300&amp;ssl=1 202w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/Ponta-de-areia-arranjo.png?resize=768%2C1139&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/Ponta-de-areia-arranjo.png?resize=690%2C1024&amp;ssl=1 690w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/Ponta-de-areia-arranjo.png?resize=696%2C1033&amp;ssl=1 696w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/Ponta-de-areia-arranjo.png?resize=1068%2C1585&amp;ssl=1 1068w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/Ponta-de-areia-arranjo.png?resize=283%2C420&amp;ssl=1 283w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/Ponta-de-areia-arranjo.png?w=1392&amp;ssl=1 1392w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/Ponta-de-areia-arranjo.png?w=2088&amp;ssl=1 2088w\" alt=\"\" width=\"696\" height=\"1033\" data-recalc-dims=\"1\" \/><\/p>\n<p><strong>Em vias gerais quando a haste est\u00e1 para cima se posiciona a direita da cabe\u00e7a da nota, se para baixo fica a esquerda da cabe\u00e7a da nota.\u00a0<\/strong><\/p>\n<p>Apenas quando se forma um grupo t\u00edpico chamado cluster \u2013 comum em instrumentos harm\u00f4nicos, as posi\u00e7\u00f5es da haste quebram a regra geral. Observe no primeiro, quarto e quinto acorde a exce\u00e7\u00e3o:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17034 td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/variacao-de-haste.png?resize=696%2C53&amp;ssl=1\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" srcset=\"https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/variacao-de-haste.png?w=2171&amp;ssl=1 2171w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/variacao-de-haste.png?resize=300%2C23&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/variacao-de-haste.png?resize=768%2C58&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/variacao-de-haste.png?resize=1024%2C78&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/variacao-de-haste.png?resize=696%2C53&amp;ssl=1 696w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/variacao-de-haste.png?resize=1068%2C81&amp;ssl=1 1068w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/variacao-de-haste.png?w=1392&amp;ssl=1 1392w, https:\/\/i0.wp.com\/blogsouzalima.com.br\/wp-content\/uploads\/2020\/07\/variacao-de-haste.png?w=2088&amp;ssl=1 2088w\" alt=\"\" width=\"696\" height=\"53\" data-recalc-dims=\"1\" \/><\/p>\n<p>Aqui no Souza Lima somos m\u00fasicos e fazemos m\u00fasica. Somos educadores e o BLOG est\u00e1 aqui por isso!<\/p>\n<h2><strong>#VemProSouzaLima, mas primeiro fique em casa!<\/strong><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Como \u00e9 definido o posicionamento da haste das notas? O posicionamento da haste \u00e9 um assunto que os livros de teoria infelizmente respondem parcialmente. Um leitor trouxe uma excelente pergunta. Vale corrigir, e chamar notas do sin\u00f4nimo de linguagem musical figuras de valor positivo. No&#8230;<\/p>\n","protected":false},"author":3,"featured_media":20887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[115,626,368,7],"class_list":["post-20918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudo","tag-blog-souza-lima","tag-como-e-definido-o-posicionamento-da-haste-das-notas","tag-destaques","tag-joao-marcondes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posicionamento da Haste das Notas | Regras da Nota\u00e7\u00e3o Musical<\/title>\n<meta name=\"description\" content=\"Saiba como \u00e9 definido o posicionamento da haste das notas na partitura. Entenda as regras da nota\u00e7\u00e3o musical no blog da Souza Lima!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posicionamento da Haste das Notas | Regras da Nota\u00e7\u00e3o Musical\" \/>\n<meta property=\"og:description\" content=\"Saiba como \u00e9 definido o posicionamento da haste das notas na partitura. Entenda as regras da nota\u00e7\u00e3o musical no blog da Souza Lima!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Souza Lima\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/souzalimaoficial\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-07T16:50:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-06T19:24:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/09\/partes-das-figuras.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Marcondes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo\u00e3o Marcondes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/\"},\"author\":{\"name\":\"Jo\u00e3o Marcondes\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/#\/schema\/person\/f6aad8444e58fb11121a921b22bed6ae\"},\"headline\":\"Como \u00e9 definido o posicionamento da haste das notas?\",\"datePublished\":\"2020-07-07T16:50:17+00:00\",\"dateModified\":\"2025-06-06T19:24:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/\"},\"wordCount\":446,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/09\/partes-das-figuras.webp\",\"keywords\":[\"blog souza lima\",\"como \u00e9 definido o posicionamento da haste das notas\",\"destaques\",\"jo\u00e3o marcondes\"],\"articleSection\":[\"Estudo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/\",\"url\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/\",\"name\":\"Posicionamento da Haste das Notas | Regras da Nota\u00e7\u00e3o Musical\",\"isPartOf\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/09\/partes-das-figuras.webp\",\"datePublished\":\"2020-07-07T16:50:17+00:00\",\"dateModified\":\"2025-06-06T19:24:22+00:00\",\"description\":\"Saiba como \u00e9 definido o posicionamento da haste das notas na partitura. Entenda as regras da nota\u00e7\u00e3o musical no blog da Souza Lima!\",\"breadcrumb\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#primaryimage\",\"url\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/09\/partes-das-figuras.webp\",\"contentUrl\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/09\/partes-das-figuras.webp\",\"width\":696,\"height\":522},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/souzalima.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como \u00e9 definido o posicionamento da haste das notas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/#website\",\"url\":\"https:\/\/souzalima.com.br\/blog\/\",\"name\":\"Blog Souza Lima\",\"description\":\"Descubra o universo musical com o Blog Souza Lima! \",\"publisher\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/souzalima.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/#organization\",\"name\":\"Blog Souza Lima\",\"url\":\"https:\/\/souzalima.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/logo-blog-escuro.png\",\"contentUrl\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/logo-blog-escuro.png\",\"width\":700,\"height\":360,\"caption\":\"Blog Souza Lima\"},\"image\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/souzalimaoficial\",\"https:\/\/www.instagram.com\/souzalimaoficial\/\",\"https:\/\/www.tiktok.com\/@souzalimaoficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/#\/schema\/person\/f6aad8444e58fb11121a921b22bed6ae\",\"name\":\"Jo\u00e3o Marcondes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g\",\"caption\":\"Jo\u00e3o Marcondes\"},\"url\":\"https:\/\/souzalima.com.br\/blog\/author\/joao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posicionamento da Haste das Notas | Regras da Nota\u00e7\u00e3o Musical","description":"Saiba como \u00e9 definido o posicionamento da haste das notas na partitura. Entenda as regras da nota\u00e7\u00e3o musical no blog da Souza Lima!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/","og_locale":"pt_BR","og_type":"article","og_title":"Posicionamento da Haste das Notas | Regras da Nota\u00e7\u00e3o Musical","og_description":"Saiba como \u00e9 definido o posicionamento da haste das notas na partitura. Entenda as regras da nota\u00e7\u00e3o musical no blog da Souza Lima!","og_url":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/","og_site_name":"Blog Souza Lima","article_publisher":"https:\/\/www.facebook.com\/souzalimaoficial","article_published_time":"2020-07-07T16:50:17+00:00","article_modified_time":"2025-06-06T19:24:22+00:00","og_image":[{"width":696,"height":522,"url":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/09\/partes-das-figuras.webp","type":"image\/webp"}],"author":"Jo\u00e3o Marcondes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jo\u00e3o Marcondes","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#article","isPartOf":{"@id":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/"},"author":{"name":"Jo\u00e3o Marcondes","@id":"https:\/\/souzalima.com.br\/blog\/#\/schema\/person\/f6aad8444e58fb11121a921b22bed6ae"},"headline":"Como \u00e9 definido o posicionamento da haste das notas?","datePublished":"2020-07-07T16:50:17+00:00","dateModified":"2025-06-06T19:24:22+00:00","mainEntityOfPage":{"@id":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/"},"wordCount":446,"commentCount":0,"publisher":{"@id":"https:\/\/souzalima.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#primaryimage"},"thumbnailUrl":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/09\/partes-das-figuras.webp","keywords":["blog souza lima","como \u00e9 definido o posicionamento da haste das notas","destaques","jo\u00e3o marcondes"],"articleSection":["Estudo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/","url":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/","name":"Posicionamento da Haste das Notas | Regras da Nota\u00e7\u00e3o Musical","isPartOf":{"@id":"https:\/\/souzalima.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#primaryimage"},"image":{"@id":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#primaryimage"},"thumbnailUrl":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/09\/partes-das-figuras.webp","datePublished":"2020-07-07T16:50:17+00:00","dateModified":"2025-06-06T19:24:22+00:00","description":"Saiba como \u00e9 definido o posicionamento da haste das notas na partitura. Entenda as regras da nota\u00e7\u00e3o musical no blog da Souza Lima!","breadcrumb":{"@id":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#primaryimage","url":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/09\/partes-das-figuras.webp","contentUrl":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/09\/partes-das-figuras.webp","width":696,"height":522},{"@type":"BreadcrumbList","@id":"https:\/\/souzalima.com.br\/blog\/como-e-definido-o-posicionamento-da-haste-das-notas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/souzalima.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Como \u00e9 definido o posicionamento da haste das notas?"}]},{"@type":"WebSite","@id":"https:\/\/souzalima.com.br\/blog\/#website","url":"https:\/\/souzalima.com.br\/blog\/","name":"Blog Souza Lima","description":"Descubra o universo musical com o Blog Souza Lima! ","publisher":{"@id":"https:\/\/souzalima.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/souzalima.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/souzalima.com.br\/blog\/#organization","name":"Blog Souza Lima","url":"https:\/\/souzalima.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/souzalima.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/logo-blog-escuro.png","contentUrl":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/logo-blog-escuro.png","width":700,"height":360,"caption":"Blog Souza Lima"},"image":{"@id":"https:\/\/souzalima.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/souzalimaoficial","https:\/\/www.instagram.com\/souzalimaoficial\/","https:\/\/www.tiktok.com\/@souzalimaoficial"]},{"@type":"Person","@id":"https:\/\/souzalima.com.br\/blog\/#\/schema\/person\/f6aad8444e58fb11121a921b22bed6ae","name":"Jo\u00e3o Marcondes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g","caption":"Jo\u00e3o Marcondes"},"url":"https:\/\/souzalima.com.br\/blog\/author\/joao\/"}]}},"_links":{"self":[{"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/posts\/20918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/comments?post=20918"}],"version-history":[{"count":1,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/posts\/20918\/revisions"}],"predecessor-version":[{"id":20919,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/posts\/20918\/revisions\/20919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/media\/20887"}],"wp:attachment":[{"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/media?parent=20918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/categories?post=20918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/tags?post=20918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}