{"id":20528,"date":"2019-07-08T09:55:10","date_gmt":"2019-07-08T12:55:10","guid":{"rendered":"https:\/\/souzalima.com.br\/blog\/?p=20528"},"modified":"2024-09-24T09:57:12","modified_gmt":"2024-09-24T12:57:12","slug":"quem-foi-joao-gilberto","status":"publish","type":"post","link":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/","title":{"rendered":"Quem foi Jo\u00e3o Gilberto?"},"content":{"rendered":"<h2>O Brasil valoriza tanto as hist\u00f3rias de sucesso esportivo, de reden\u00e7\u00e3o, de conquistas internacionais, seja de um nadador, de um tenista, de um ou dois pilotos, e de dezenas de futebol\u00edsticas, para t\u00e3o pouco valorizar os artistas que aqui foram forjados?<\/h2>\n<p>Jo\u00e3o Gilberto morreu neste s\u00e1bado frio, seis de julho de 2019, praticamente sessenta anos depois do lan\u00e7amento de seu disco <em>Chega de Saudade. <\/em>E Jo\u00e3o Gilberto como ant\u00edtese de tudo que comp\u00f5e os conceitos superlativos; se de um violonista virtuoso e r\u00e1pido, que n\u00e3o era; se de um cantor de pot\u00eancia, que se era preferia esconder. De int\u00e9rprete que da bossa-nova que s\u00f3 teve como algoz um per\u00edodo, j\u00e1 que Jo\u00e3o se encantou em cantar as composi\u00e7\u00f5es brasileiras e latinas que vinham desde a d\u00e9cada de 1940.<\/p>\n<p>Recluso em uma genialidade inesperada. E inesperada porque o Brasil tamb\u00e9m maltrata seus migrantes. Jo\u00e3o Gilberto nascido em Juazeiro, Bahia, antes de se consolidar o artista que foi, transitou por cidades e estados brasileiros. Ficou conhecido aos 26 anos de idade, e reconhecido ao <strong>mundo<\/strong> poucos anos depois.<\/p>\n<p><strong>Hoje deveria ser feriado nacional! E n\u00e3o \u00e9! Solenidades deveriam mover nosso pa\u00eds como se faz para as maiores personalidades em outros pa\u00edses. Mas no Brasil n\u00e3o \u00e9 assim.<\/strong><\/p>\n<h2><strong>Quem \u00e9 Jo\u00e3o Gilberto aqui? Se eu dissesse que parece que ningu\u00e9m voc\u00ea acreditaria?<\/strong><\/h2>\n<p>O Presidente do Brasil declarou depois de perguntado que lamenta a morte dessa pessoa que \u00e9 \u201cconhecida\u201d, e desejou condol\u00eancia a fam\u00edlia do conhecido, repito depois de perguntado afirmou que lamenta a morte dessa pessoa que \u00e9 \u201cConhecida\u201d.<\/p>\n<p>N\u00e3o Presidente Bolsonaro, n\u00e3o mesmo!<\/p>\n<h2><strong>Jo\u00e3o Gilberto n\u00e3o \u00e9 conhecido, \u00e9 reconhecido, aclamado, vangloriado, enaltecido, reverenciado, exaltado no mundo\u2026<\/strong><\/h2>\n<p>Aqui n\u00e3o t\u00eam luto nacional pela perda desse monumento do fazer musical e art\u00edstico brasileiro. E o problema n\u00e3o \u00e9 do presidente que recentemente publicou lamenta\u00e7\u00f5es profundas a um personagem chamado MC Rea\u00e7a (de reacion\u00e1rio), valorizando \u201cseu Dom e ampla contribui\u00e7\u00e3o para um Brasil melhor\u201d, esse personagem que agrediu a amante que estava gr\u00e1vida e se matou a seguir. Essa homenagem p\u00f3stuma ao MC Rea\u00e7a feira pelo presidente da Rep\u00fablica do Brasil foi publicada no Twitter no dia 2 de junho. Quem? O problema \u00e9 da forma que o Brasil se comunica.<\/p>\n<p><strong><em>N\u00e3o h\u00e1 no Brasil uma emissora de r\u00e1dio especializada em Bossa-Nova. D\u00e1 pra acreditar?<\/em><\/strong><\/p>\n<p>As emissoras s\u00e3o dominadas por oligarquias. Por exemplo, o candidato a presidente do pleito de 2014 possui uma dezena de frequ\u00eancias de r\u00e1dio, concedidas ao longo da ditadura militar brasileira.<\/p>\n<h2><strong>O Brasil melhor<\/strong><\/h2>\n<p>Jo\u00e3o Gilberto, senhor presidente \u00e9 a pessoa para se dizer da ampla contribui\u00e7\u00e3o para o Brasil melhor. Cada vez que saio do pa\u00eds, presidente, para falar sobre m\u00fasica recebo o quanto se valoriza a bossa-nova de Jo\u00e3o Gilberto. Embora nem sei se Jo\u00e3o Gilberto \u00e9 bossa-nova, s\u00f3 sei que ele \u00e9 muito mais que o Brasil dos esportistas que deu certo.<\/p>\n<p><strong><em>Quem quer saber de Copa Am\u00e9rica? \u00c9 luto.<\/em><\/strong><\/p>\n<p>Quantos int\u00e9rpretes mudaram a m\u00fasica do mundo, presidente? Sim, Jo\u00e3o Gilberto era um int\u00e9rprete, aquele que reconstr\u00f3i uma composi\u00e7\u00e3o sem compor. E mudou a forma de se fazer m\u00fasica no mundo.<\/p>\n<p>Posso garantir que eu, quem escreve esse misto de homenagem e desabafo, n\u00e3o estaria aqui se n\u00e3o fosse Jo\u00e3o Gilberto.<\/p>\n<p>Nosso BLOG n\u00e3o fala de pol\u00edtica, n\u00e3o fala de direita ou de esquerda, nosso BLOG se contenta em orientar novos m\u00fasicos e estudantes, falar da m\u00fasica brasileira de maneira a guiar ouvidos, mas s\u00f3 existe por vontade de uma pessoa que lamenta o Brasil enterrar hoje seu maior artista, quase que anonimamente.<\/p>\n<p>No Brasil foi implementado desde 2017 um status quo de persegui\u00e7\u00e3o p\u00fablica para quem vive de arte.<\/p>\n<h2><strong>O Brasil desde o in\u00edcio de 2019 n\u00e3o tem mais Minist\u00e9rio da Cultura.<\/strong><\/h2>\n<p>Que espa\u00e7o n\u00f3s temos para lamentar a viol\u00eancia que vivemos? O espa\u00e7o que n\u00f3s mesmos criamos?<\/p>\n<p>O presidente vai passar como outros j\u00e1 passaram. Direita, esquerda, centro, o que for. Mas ainda falaremos de Jo\u00e3o Gilberto. Quem \u00e9 o conhecido ent\u00e3o?<\/p>\n<p>Obrigado Jo\u00e3o Gilberto simplesmente por ter existido, insistido, e consolidado uma obra pequena em n\u00famero de fonogramas, mas imensa em realiza\u00e7\u00e3o. Um tal de Frank Sinatra registrou dois discos com repert\u00f3rio de Tom Jobim, mas a voz que ecoa o maestro soberano desse pa\u00eds de esquecimento chama-se Jo\u00e3o Gilberto.<\/p>\n<p>Ou\u00e7a a obra completa, n\u00e3o h\u00e1 orienta\u00e7\u00e3o melhor. Habitue-se que mesmo seis d\u00e9cadas ap\u00f3s o lan\u00e7amento de seu primeiro fonograma, o que fez esse artista ainda \u00e9 novo.<\/p>\n<p>#VemProSouzaLima<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil valoriza tanto as hist\u00f3rias de sucesso esportivo, de reden\u00e7\u00e3o, de conquistas internacionais, seja de um nadador, de um tenista, de um ou dois pilotos, e de dezenas de futebol\u00edsticas, para t\u00e3o pouco valorizar os artistas que aqui foram forjados? Jo\u00e3o Gilberto morreu neste&#8230;<\/p>\n","protected":false},"author":3,"featured_media":19491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[115,368,472,7,471],"class_list":["post-20528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-blog-souza-lima","tag-destaques","tag-joao-gilberto","tag-joao-marcondes","tag-quem-foi-joao-gilberto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quem foi Jo\u00e3o Gilberto? - Blog Souza Lima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quem foi Jo\u00e3o Gilberto? - Blog Souza Lima\" \/>\n<meta property=\"og:description\" content=\"O Brasil valoriza tanto as hist\u00f3rias de sucesso esportivo, de reden\u00e7\u00e3o, de conquistas internacionais, seja de um nadador, de um tenista, de um ou dois pilotos, e de dezenas de futebol\u00edsticas, para t\u00e3o pouco valorizar os artistas que aqui foram forjados? Jo\u00e3o Gilberto morreu neste...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Souza Lima\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/souzalimaoficial\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-08T12:55:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-24T12:57:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/quais-notas-fazem-parte-dos-acordes-que-tem-si-como-tonica-ou-fundamental.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Marcondes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo\u00e3o Marcondes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/\"},\"author\":{\"name\":\"Jo\u00e3o Marcondes\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/#\/schema\/person\/f6aad8444e58fb11121a921b22bed6ae\"},\"headline\":\"Quem foi Jo\u00e3o Gilberto?\",\"datePublished\":\"2019-07-08T12:55:10+00:00\",\"dateModified\":\"2024-09-24T12:57:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/\"},\"wordCount\":814,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/quais-notas-fazem-parte-dos-acordes-que-tem-si-como-tonica-ou-fundamental.jpg\",\"keywords\":[\"blog souza lima\",\"destaques\",\"jo\u00e3o gilberto\",\"jo\u00e3o marcondes\",\"quem foi jo\u00e3o gilberto\"],\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/\",\"url\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/\",\"name\":\"Quem foi Jo\u00e3o Gilberto? - Blog Souza Lima\",\"isPartOf\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/quais-notas-fazem-parte-dos-acordes-que-tem-si-como-tonica-ou-fundamental.jpg\",\"datePublished\":\"2019-07-08T12:55:10+00:00\",\"dateModified\":\"2024-09-24T12:57:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#primaryimage\",\"url\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/quais-notas-fazem-parte-dos-acordes-que-tem-si-como-tonica-ou-fundamental.jpg\",\"contentUrl\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/quais-notas-fazem-parte-dos-acordes-que-tem-si-como-tonica-ou-fundamental.jpg\",\"width\":1000,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/souzalima.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quem foi Jo\u00e3o Gilberto?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/#website\",\"url\":\"https:\/\/souzalima.com.br\/blog\/\",\"name\":\"Blog Souza Lima\",\"description\":\"Descubra o universo musical com o Blog Souza Lima! \",\"publisher\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/souzalima.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/#organization\",\"name\":\"Blog Souza Lima\",\"url\":\"https:\/\/souzalima.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/logo-blog-escuro.png\",\"contentUrl\":\"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/logo-blog-escuro.png\",\"width\":700,\"height\":360,\"caption\":\"Blog Souza Lima\"},\"image\":{\"@id\":\"https:\/\/souzalima.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/souzalimaoficial\",\"https:\/\/www.instagram.com\/souzalimaoficial\/\",\"https:\/\/www.tiktok.com\/@souzalimaoficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/souzalima.com.br\/blog\/#\/schema\/person\/f6aad8444e58fb11121a921b22bed6ae\",\"name\":\"Jo\u00e3o Marcondes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g\",\"caption\":\"Jo\u00e3o Marcondes\"},\"url\":\"https:\/\/souzalima.com.br\/blog\/author\/joao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quem foi Jo\u00e3o Gilberto? - Blog Souza Lima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/","og_locale":"pt_BR","og_type":"article","og_title":"Quem foi Jo\u00e3o Gilberto? - Blog Souza Lima","og_description":"O Brasil valoriza tanto as hist\u00f3rias de sucesso esportivo, de reden\u00e7\u00e3o, de conquistas internacionais, seja de um nadador, de um tenista, de um ou dois pilotos, e de dezenas de futebol\u00edsticas, para t\u00e3o pouco valorizar os artistas que aqui foram forjados? Jo\u00e3o Gilberto morreu neste...","og_url":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/","og_site_name":"Blog Souza Lima","article_publisher":"https:\/\/www.facebook.com\/souzalimaoficial","article_published_time":"2019-07-08T12:55:10+00:00","article_modified_time":"2024-09-24T12:57:12+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/quais-notas-fazem-parte-dos-acordes-que-tem-si-como-tonica-ou-fundamental.jpg","type":"image\/jpeg"}],"author":"Jo\u00e3o Marcondes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jo\u00e3o Marcondes","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#article","isPartOf":{"@id":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/"},"author":{"name":"Jo\u00e3o Marcondes","@id":"https:\/\/souzalima.com.br\/blog\/#\/schema\/person\/f6aad8444e58fb11121a921b22bed6ae"},"headline":"Quem foi Jo\u00e3o Gilberto?","datePublished":"2019-07-08T12:55:10+00:00","dateModified":"2024-09-24T12:57:12+00:00","mainEntityOfPage":{"@id":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/"},"wordCount":814,"commentCount":0,"publisher":{"@id":"https:\/\/souzalima.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#primaryimage"},"thumbnailUrl":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/quais-notas-fazem-parte-dos-acordes-que-tem-si-como-tonica-ou-fundamental.jpg","keywords":["blog souza lima","destaques","jo\u00e3o gilberto","jo\u00e3o marcondes","quem foi jo\u00e3o gilberto"],"articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/","url":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/","name":"Quem foi Jo\u00e3o Gilberto? - Blog Souza Lima","isPartOf":{"@id":"https:\/\/souzalima.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#primaryimage"},"image":{"@id":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#primaryimage"},"thumbnailUrl":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/quais-notas-fazem-parte-dos-acordes-que-tem-si-como-tonica-ou-fundamental.jpg","datePublished":"2019-07-08T12:55:10+00:00","dateModified":"2024-09-24T12:57:12+00:00","breadcrumb":{"@id":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#primaryimage","url":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/quais-notas-fazem-parte-dos-acordes-que-tem-si-como-tonica-ou-fundamental.jpg","contentUrl":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/quais-notas-fazem-parte-dos-acordes-que-tem-si-como-tonica-ou-fundamental.jpg","width":1000,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/souzalima.com.br\/blog\/quem-foi-joao-gilberto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/souzalima.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Quem foi Jo\u00e3o Gilberto?"}]},{"@type":"WebSite","@id":"https:\/\/souzalima.com.br\/blog\/#website","url":"https:\/\/souzalima.com.br\/blog\/","name":"Blog Souza Lima","description":"Descubra o universo musical com o Blog Souza Lima! ","publisher":{"@id":"https:\/\/souzalima.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/souzalima.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/souzalima.com.br\/blog\/#organization","name":"Blog Souza Lima","url":"https:\/\/souzalima.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/souzalima.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/logo-blog-escuro.png","contentUrl":"https:\/\/souzalima.com.br\/blog\/wp-content\/uploads\/2024\/04\/logo-blog-escuro.png","width":700,"height":360,"caption":"Blog Souza Lima"},"image":{"@id":"https:\/\/souzalima.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/souzalimaoficial","https:\/\/www.instagram.com\/souzalimaoficial\/","https:\/\/www.tiktok.com\/@souzalimaoficial"]},{"@type":"Person","@id":"https:\/\/souzalima.com.br\/blog\/#\/schema\/person\/f6aad8444e58fb11121a921b22bed6ae","name":"Jo\u00e3o Marcondes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ceaf49983887d9fed6c838ba33a97c89f1e3f2836978af414e1b7cf88be2678?s=96&d=mm&r=g","caption":"Jo\u00e3o Marcondes"},"url":"https:\/\/souzalima.com.br\/blog\/author\/joao\/"}]}},"_links":{"self":[{"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/posts\/20528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/comments?post=20528"}],"version-history":[{"count":1,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/posts\/20528\/revisions"}],"predecessor-version":[{"id":20529,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/posts\/20528\/revisions\/20529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/media\/19491"}],"wp:attachment":[{"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/media?parent=20528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/categories?post=20528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/souzalima.com.br\/blog\/wp-json\/wp\/v2\/tags?post=20528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}